{"id":767,"date":"2024-03-19T17:41:18","date_gmt":"2024-03-19T16:41:18","guid":{"rendered":"https:\/\/redivium.com\/financial-reports\/"},"modified":"2024-09-30T12:13:51","modified_gmt":"2024-09-30T10:13:51","slug":"finanzberichte","status":"publish","type":"page","link":"https:\/\/redivium.com\/de\/finanzberichte\/","title":{"rendered":"Finanzberichte"},"content":{"rendered":"\n<div class=\"redivium-documents pt-1 mx-auto px-8 md:py-16 py-8 container\">\n    <div class=\"\">\n        <div class=\"md:w-1\/2 w-full\">\n            <h2 class=\"md:text-display2 text-subheading1 mt-8 text-primary font-normal\">2024<\/h2>\n        <\/div>\n\n        <div class=\"\">\n            <div class=\"grid grid-cols-12 gap-x-2 gap-y-8 sm:gap-x-8 py-4 border-b\" style=\"\n                        border-image: linear-gradient(to right, #565DA9, #00A880);\n                        border-bottom-width: 4px;\n                        border-image-repeat: stretch;\n                        border-image-slice: 1;\n                        \">\n\n                <div class=\"col-span-10\">\n                    <p class=\"text-subheading2 text-gray-400\">\n                        TITEL                    <\/p>\n                <\/div>\n                <div class=\"col-span-2\">\n\n                <\/div>\n            <\/div>\n\n\n                        <div class=\"grid grid-cols-12 gap-x-2 gap-y-12 sm:gap-x-8 border-b py-8 border-primary\">\n\n                <div class=\"lg:col-span-10 col-span-10 items-center self-center\">\n\n                    <p class=\"text-subheading2 text-primary font-light mt-0 items-center self-center mb-0\">\n                        Jahresbericht | September, 2024                    <\/p>\n                <\/div>\n                <div class=\"col-span-2 self-center\">\n                    <a href=\"https:\/\/redivium.com\/wp-content\/uploads\/2024\/09\/068hwql691385d.pdf\" target=\"_blank\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"30\" viewBox=\"0 0 28 30\" fill=\"none\">\n                            <g id=\"u:file-download\">\n                                <g id=\"Union\">\n                                    <path d=\"M6.00086 9V12H10.5015V9H6.00086Z\" fill=\"url(#paint0_radial_69_2953)\" \/>\n                                    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n                                        d=\"M4.50064 27C4.10276 27 3.72118 26.842 3.43983 26.5607C3.15849 26.2794 3.00043 25.8978 3.00043 25.5V4.5C3.00043 4.10218 3.15849 3.72064 3.43983 3.43934C3.72118 3.15804 4.10276 3 4.50064 3H12.0017V7.5C12.0017 8.69347 12.4759 9.83807 13.3199 10.682C14.164 11.5259 15.3087 12 16.5024 12H21.003V19.5L24.0034 16.5V10.41C23.9878 10.2722 23.9576 10.1364 23.9134 10.005V9.87C23.8413 9.71577 23.7451 9.574 23.6284 9.45L14.6271 0.45C14.5031 0.333324 14.3613 0.237121 14.207 0.165C14.1574 0.156314 14.1066 0.156314 14.057 0.165C13.9111 0.0870046 13.7544 0.031383 13.5919 0H0V30H16.5024V27H4.50064ZM15.0021 5.115L18.8877 9H16.5024C16.1045 9 15.7229 8.84196 15.4415 8.56066C15.1602 8.27936 15.0021 7.89782 15.0021 7.5V5.115Z\"\n                                        fill=\"url(#paint1_radial_69_2953)\" \/>\n                                    <path d=\"M6.00086 15H18.0026V18H6.00086V15Z\" fill=\"url(#paint2_radial_69_2953)\" \/>\n                                    <path d=\"M15.0021 21V24H6.00086V21H15.0021Z\" fill=\"url(#paint3_radial_69_2953)\" \/>\n                                    <path\n                                        d=\"M20.3049 28.0143L22.4942 30L27.93 25.0696L25.7407 23.0839L24.0034 24.6597L24.0034 19.5L21.003 22.5L21.003 24.6726L19.2514 23.0839L17.0621 25.0696L20.3068 28.0126L20.3049 28.0143Z\"\n                                        fill=\"url(#paint4_radial_69_2953)\" \/>\n                                <\/g>\n                            <\/g>\n                            <defs>\n                                <radialGradient id=\"paint0_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint1_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint2_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint3_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint4_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                            <\/defs>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n                        <div class=\"grid grid-cols-12 gap-x-2 gap-y-12 sm:gap-x-8 border-b py-8 border-primary\">\n\n                <div class=\"lg:col-span-10 col-span-10 items-center self-center\">\n\n                    <p class=\"text-subheading2 text-primary font-light mt-0 items-center self-center mb-0\">\n                        Halbjahresbericht | M\u00e4rz, 2024                    <\/p>\n                <\/div>\n                <div class=\"col-span-2 self-center\">\n                    <a href=\"https:\/\/redivium.com\/wp-content\/uploads\/2024\/03\/121821-RIL-240312-ASX-Annc-HY-report-Dec23-FINAL.pdf\" target=\"_blank\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"30\" viewBox=\"0 0 28 30\" fill=\"none\">\n                            <g id=\"u:file-download\">\n                                <g id=\"Union\">\n                                    <path d=\"M6.00086 9V12H10.5015V9H6.00086Z\" fill=\"url(#paint0_radial_69_2953)\" \/>\n                                    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n                                        d=\"M4.50064 27C4.10276 27 3.72118 26.842 3.43983 26.5607C3.15849 26.2794 3.00043 25.8978 3.00043 25.5V4.5C3.00043 4.10218 3.15849 3.72064 3.43983 3.43934C3.72118 3.15804 4.10276 3 4.50064 3H12.0017V7.5C12.0017 8.69347 12.4759 9.83807 13.3199 10.682C14.164 11.5259 15.3087 12 16.5024 12H21.003V19.5L24.0034 16.5V10.41C23.9878 10.2722 23.9576 10.1364 23.9134 10.005V9.87C23.8413 9.71577 23.7451 9.574 23.6284 9.45L14.6271 0.45C14.5031 0.333324 14.3613 0.237121 14.207 0.165C14.1574 0.156314 14.1066 0.156314 14.057 0.165C13.9111 0.0870046 13.7544 0.031383 13.5919 0H0V30H16.5024V27H4.50064ZM15.0021 5.115L18.8877 9H16.5024C16.1045 9 15.7229 8.84196 15.4415 8.56066C15.1602 8.27936 15.0021 7.89782 15.0021 7.5V5.115Z\"\n                                        fill=\"url(#paint1_radial_69_2953)\" \/>\n                                    <path d=\"M6.00086 15H18.0026V18H6.00086V15Z\" fill=\"url(#paint2_radial_69_2953)\" \/>\n                                    <path d=\"M15.0021 21V24H6.00086V21H15.0021Z\" fill=\"url(#paint3_radial_69_2953)\" \/>\n                                    <path\n                                        d=\"M20.3049 28.0143L22.4942 30L27.93 25.0696L25.7407 23.0839L24.0034 24.6597L24.0034 19.5L21.003 22.5L21.003 24.6726L19.2514 23.0839L17.0621 25.0696L20.3068 28.0126L20.3049 28.0143Z\"\n                                        fill=\"url(#paint4_radial_69_2953)\" \/>\n                                <\/g>\n                            <\/g>\n                            <defs>\n                                <radialGradient id=\"paint0_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint1_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint2_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint3_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint4_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                            <\/defs>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n                        <div id=\"post-list\">\n\n            <\/div>\n        <\/div>\n\n    <\/div>\n<\/div>\n\n<script type=\"text\/javascript\">\njQuery(function($) {\n    $('#load-more').on('click', function() {\n        var page = $(this).data('page');\n        var newPage = page + 1;\n        var ajaxurl = 'https:\/\/redivium.com\/wp-admin\/admin-ajax.php';\n\n        $.ajax({\n            url: ajaxurl,\n            type: 'POST',\n            data: {\n                page: page,\n                action: 'load_news'\n            },\n            error: function(response) {\n                console.log(response);\n                console.log(ajaxurl);\n            },\n            success: function(response) {\n                console.log(response);\n                $('#post-list').append(response.html);\n                $('#load-more').data('page', newPage);\n\n                if (response.next_page_exists !== true) {\n                    $('#load-more-wrap').hide();\n                }\n            }\n        });\n    });\n});\n<\/script>\n\n\n\n<div class=\"redivium-documents pt-1 mx-auto px-8 md:py-16 py-8 container\">\n    <div class=\"\">\n        <div class=\"md:w-1\/2 w-full\">\n            <h2 class=\"md:text-display2 text-subheading1 mt-8 text-primary font-normal\">2023<\/h2>\n        <\/div>\n\n        <div class=\"\">\n            <div class=\"grid grid-cols-12 gap-x-2 gap-y-8 sm:gap-x-8 py-4 border-b\" style=\"\n                        border-image: linear-gradient(to right, #565DA9, #00A880);\n                        border-bottom-width: 4px;\n                        border-image-repeat: stretch;\n                        border-image-slice: 1;\n                        \">\n\n                <div class=\"col-span-10\">\n                    <p class=\"text-subheading2 text-gray-400\">\n                        TITEL                    <\/p>\n                <\/div>\n                <div class=\"col-span-2\">\n\n                <\/div>\n            <\/div>\n\n\n                        <div class=\"grid grid-cols-12 gap-x-2 gap-y-12 sm:gap-x-8 border-b py-8 border-primary\">\n\n                <div class=\"lg:col-span-10 col-span-10 items-center self-center\">\n\n                    <p class=\"text-subheading2 text-primary font-light mt-0 items-center self-center mb-0\">\n                        Jahresbericht | September, 2023                    <\/p>\n                <\/div>\n                <div class=\"col-span-2 self-center\">\n                    <a href=\"https:\/\/redivium.com\/wp-content\/uploads\/2024\/03\/05v4m3zz42d5fd.pdf\" target=\"_blank\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"30\" viewBox=\"0 0 28 30\" fill=\"none\">\n                            <g id=\"u:file-download\">\n                                <g id=\"Union\">\n                                    <path d=\"M6.00086 9V12H10.5015V9H6.00086Z\" fill=\"url(#paint0_radial_69_2953)\" \/>\n                                    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n                                        d=\"M4.50064 27C4.10276 27 3.72118 26.842 3.43983 26.5607C3.15849 26.2794 3.00043 25.8978 3.00043 25.5V4.5C3.00043 4.10218 3.15849 3.72064 3.43983 3.43934C3.72118 3.15804 4.10276 3 4.50064 3H12.0017V7.5C12.0017 8.69347 12.4759 9.83807 13.3199 10.682C14.164 11.5259 15.3087 12 16.5024 12H21.003V19.5L24.0034 16.5V10.41C23.9878 10.2722 23.9576 10.1364 23.9134 10.005V9.87C23.8413 9.71577 23.7451 9.574 23.6284 9.45L14.6271 0.45C14.5031 0.333324 14.3613 0.237121 14.207 0.165C14.1574 0.156314 14.1066 0.156314 14.057 0.165C13.9111 0.0870046 13.7544 0.031383 13.5919 0H0V30H16.5024V27H4.50064ZM15.0021 5.115L18.8877 9H16.5024C16.1045 9 15.7229 8.84196 15.4415 8.56066C15.1602 8.27936 15.0021 7.89782 15.0021 7.5V5.115Z\"\n                                        fill=\"url(#paint1_radial_69_2953)\" \/>\n                                    <path d=\"M6.00086 15H18.0026V18H6.00086V15Z\" fill=\"url(#paint2_radial_69_2953)\" \/>\n                                    <path d=\"M15.0021 21V24H6.00086V21H15.0021Z\" fill=\"url(#paint3_radial_69_2953)\" \/>\n                                    <path\n                                        d=\"M20.3049 28.0143L22.4942 30L27.93 25.0696L25.7407 23.0839L24.0034 24.6597L24.0034 19.5L21.003 22.5L21.003 24.6726L19.2514 23.0839L17.0621 25.0696L20.3068 28.0126L20.3049 28.0143Z\"\n                                        fill=\"url(#paint4_radial_69_2953)\" \/>\n                                <\/g>\n                            <\/g>\n                            <defs>\n                                <radialGradient id=\"paint0_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint1_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint2_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint3_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint4_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                            <\/defs>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n                        <div class=\"grid grid-cols-12 gap-x-2 gap-y-12 sm:gap-x-8 border-b py-8 border-primary\">\n\n                <div class=\"lg:col-span-10 col-span-10 items-center self-center\">\n\n                    <p class=\"text-subheading2 text-primary font-light mt-0 items-center self-center mb-0\">\n                        Halbjahresbericht | M\u00e4rz, 2023                    <\/p>\n                <\/div>\n                <div class=\"col-span-2 self-center\">\n                    <a href=\"https:\/\/redivium.com\/wp-content\/uploads\/2024\/03\/121773-HNR-230310-ASX-Annc-HY-report-311222-04-230309_FINAL-signed.pdf\" target=\"_blank\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"30\" viewBox=\"0 0 28 30\" fill=\"none\">\n                            <g id=\"u:file-download\">\n                                <g id=\"Union\">\n                                    <path d=\"M6.00086 9V12H10.5015V9H6.00086Z\" fill=\"url(#paint0_radial_69_2953)\" \/>\n                                    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n                                        d=\"M4.50064 27C4.10276 27 3.72118 26.842 3.43983 26.5607C3.15849 26.2794 3.00043 25.8978 3.00043 25.5V4.5C3.00043 4.10218 3.15849 3.72064 3.43983 3.43934C3.72118 3.15804 4.10276 3 4.50064 3H12.0017V7.5C12.0017 8.69347 12.4759 9.83807 13.3199 10.682C14.164 11.5259 15.3087 12 16.5024 12H21.003V19.5L24.0034 16.5V10.41C23.9878 10.2722 23.9576 10.1364 23.9134 10.005V9.87C23.8413 9.71577 23.7451 9.574 23.6284 9.45L14.6271 0.45C14.5031 0.333324 14.3613 0.237121 14.207 0.165C14.1574 0.156314 14.1066 0.156314 14.057 0.165C13.9111 0.0870046 13.7544 0.031383 13.5919 0H0V30H16.5024V27H4.50064ZM15.0021 5.115L18.8877 9H16.5024C16.1045 9 15.7229 8.84196 15.4415 8.56066C15.1602 8.27936 15.0021 7.89782 15.0021 7.5V5.115Z\"\n                                        fill=\"url(#paint1_radial_69_2953)\" \/>\n                                    <path d=\"M6.00086 15H18.0026V18H6.00086V15Z\" fill=\"url(#paint2_radial_69_2953)\" \/>\n                                    <path d=\"M15.0021 21V24H6.00086V21H15.0021Z\" fill=\"url(#paint3_radial_69_2953)\" \/>\n                                    <path\n                                        d=\"M20.3049 28.0143L22.4942 30L27.93 25.0696L25.7407 23.0839L24.0034 24.6597L24.0034 19.5L21.003 22.5L21.003 24.6726L19.2514 23.0839L17.0621 25.0696L20.3068 28.0126L20.3049 28.0143Z\"\n                                        fill=\"url(#paint4_radial_69_2953)\" \/>\n                                <\/g>\n                            <\/g>\n                            <defs>\n                                <radialGradient id=\"paint0_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint1_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint2_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint3_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint4_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                            <\/defs>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n                        <div id=\"post-list\">\n\n            <\/div>\n        <\/div>\n\n    <\/div>\n<\/div>\n\n<script type=\"text\/javascript\">\njQuery(function($) {\n    $('#load-more').on('click', function() {\n        var page = $(this).data('page');\n        var newPage = page + 1;\n        var ajaxurl = 'https:\/\/redivium.com\/wp-admin\/admin-ajax.php';\n\n        $.ajax({\n            url: ajaxurl,\n            type: 'POST',\n            data: {\n                page: page,\n                action: 'load_news'\n            },\n            error: function(response) {\n                console.log(response);\n                console.log(ajaxurl);\n            },\n            success: function(response) {\n                console.log(response);\n                $('#post-list').append(response.html);\n                $('#load-more').data('page', newPage);\n\n                if (response.next_page_exists !== true) {\n                    $('#load-more-wrap').hide();\n                }\n            }\n        });\n    });\n});\n<\/script>\n\n\n\n<div class=\"redivium-documents pt-1 mx-auto px-8 md:py-16 py-8 container\">\n    <div class=\"\">\n        <div class=\"md:w-1\/2 w-full\">\n            <h2 class=\"md:text-display2 text-subheading1 mt-8 text-primary font-normal\">2022<\/h2>\n        <\/div>\n\n        <div class=\"\">\n            <div class=\"grid grid-cols-12 gap-x-2 gap-y-8 sm:gap-x-8 py-4 border-b\" style=\"\n                        border-image: linear-gradient(to right, #565DA9, #00A880);\n                        border-bottom-width: 4px;\n                        border-image-repeat: stretch;\n                        border-image-slice: 1;\n                        \">\n\n                <div class=\"col-span-10\">\n                    <p class=\"text-subheading2 text-gray-400\">\n                        TITEL                    <\/p>\n                <\/div>\n                <div class=\"col-span-2\">\n\n                <\/div>\n            <\/div>\n\n\n                        <div class=\"grid grid-cols-12 gap-x-2 gap-y-12 sm:gap-x-8 border-b py-8 border-primary\">\n\n                <div class=\"lg:col-span-10 col-span-10 items-center self-center\">\n\n                    <p class=\"text-subheading2 text-primary font-light mt-0 items-center self-center mb-0\">\n                        Jahresbericht | September, 2022                    <\/p>\n                <\/div>\n                <div class=\"col-span-2 self-center\">\n                    <a href=\"https:\/\/redivium.com\/wp-content\/uploads\/2024\/03\/2441887.pdf\" target=\"_blank\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"30\" viewBox=\"0 0 28 30\" fill=\"none\">\n                            <g id=\"u:file-download\">\n                                <g id=\"Union\">\n                                    <path d=\"M6.00086 9V12H10.5015V9H6.00086Z\" fill=\"url(#paint0_radial_69_2953)\" \/>\n                                    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n                                        d=\"M4.50064 27C4.10276 27 3.72118 26.842 3.43983 26.5607C3.15849 26.2794 3.00043 25.8978 3.00043 25.5V4.5C3.00043 4.10218 3.15849 3.72064 3.43983 3.43934C3.72118 3.15804 4.10276 3 4.50064 3H12.0017V7.5C12.0017 8.69347 12.4759 9.83807 13.3199 10.682C14.164 11.5259 15.3087 12 16.5024 12H21.003V19.5L24.0034 16.5V10.41C23.9878 10.2722 23.9576 10.1364 23.9134 10.005V9.87C23.8413 9.71577 23.7451 9.574 23.6284 9.45L14.6271 0.45C14.5031 0.333324 14.3613 0.237121 14.207 0.165C14.1574 0.156314 14.1066 0.156314 14.057 0.165C13.9111 0.0870046 13.7544 0.031383 13.5919 0H0V30H16.5024V27H4.50064ZM15.0021 5.115L18.8877 9H16.5024C16.1045 9 15.7229 8.84196 15.4415 8.56066C15.1602 8.27936 15.0021 7.89782 15.0021 7.5V5.115Z\"\n                                        fill=\"url(#paint1_radial_69_2953)\" \/>\n                                    <path d=\"M6.00086 15H18.0026V18H6.00086V15Z\" fill=\"url(#paint2_radial_69_2953)\" \/>\n                                    <path d=\"M15.0021 21V24H6.00086V21H15.0021Z\" fill=\"url(#paint3_radial_69_2953)\" \/>\n                                    <path\n                                        d=\"M20.3049 28.0143L22.4942 30L27.93 25.0696L25.7407 23.0839L24.0034 24.6597L24.0034 19.5L21.003 22.5L21.003 24.6726L19.2514 23.0839L17.0621 25.0696L20.3068 28.0126L20.3049 28.0143Z\"\n                                        fill=\"url(#paint4_radial_69_2953)\" \/>\n                                <\/g>\n                            <\/g>\n                            <defs>\n                                <radialGradient id=\"paint0_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint1_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint2_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint3_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint4_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                            <\/defs>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n                        <div class=\"grid grid-cols-12 gap-x-2 gap-y-12 sm:gap-x-8 border-b py-8 border-primary\">\n\n                <div class=\"lg:col-span-10 col-span-10 items-center self-center\">\n\n                    <p class=\"text-subheading2 text-primary font-light mt-0 items-center self-center mb-0\">\n                        Halbjahresbericht | March, 2022                    <\/p>\n                <\/div>\n                <div class=\"col-span-2 self-center\">\n                    <a href=\"https:\/\/redivium.com\/wp-content\/uploads\/2024\/03\/121691-HNR-220311-HY-report-311221.pdf\" target=\"_blank\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"30\" viewBox=\"0 0 28 30\" fill=\"none\">\n                            <g id=\"u:file-download\">\n                                <g id=\"Union\">\n                                    <path d=\"M6.00086 9V12H10.5015V9H6.00086Z\" fill=\"url(#paint0_radial_69_2953)\" \/>\n                                    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n                                        d=\"M4.50064 27C4.10276 27 3.72118 26.842 3.43983 26.5607C3.15849 26.2794 3.00043 25.8978 3.00043 25.5V4.5C3.00043 4.10218 3.15849 3.72064 3.43983 3.43934C3.72118 3.15804 4.10276 3 4.50064 3H12.0017V7.5C12.0017 8.69347 12.4759 9.83807 13.3199 10.682C14.164 11.5259 15.3087 12 16.5024 12H21.003V19.5L24.0034 16.5V10.41C23.9878 10.2722 23.9576 10.1364 23.9134 10.005V9.87C23.8413 9.71577 23.7451 9.574 23.6284 9.45L14.6271 0.45C14.5031 0.333324 14.3613 0.237121 14.207 0.165C14.1574 0.156314 14.1066 0.156314 14.057 0.165C13.9111 0.0870046 13.7544 0.031383 13.5919 0H0V30H16.5024V27H4.50064ZM15.0021 5.115L18.8877 9H16.5024C16.1045 9 15.7229 8.84196 15.4415 8.56066C15.1602 8.27936 15.0021 7.89782 15.0021 7.5V5.115Z\"\n                                        fill=\"url(#paint1_radial_69_2953)\" \/>\n                                    <path d=\"M6.00086 15H18.0026V18H6.00086V15Z\" fill=\"url(#paint2_radial_69_2953)\" \/>\n                                    <path d=\"M15.0021 21V24H6.00086V21H15.0021Z\" fill=\"url(#paint3_radial_69_2953)\" \/>\n                                    <path\n                                        d=\"M20.3049 28.0143L22.4942 30L27.93 25.0696L25.7407 23.0839L24.0034 24.6597L24.0034 19.5L21.003 22.5L21.003 24.6726L19.2514 23.0839L17.0621 25.0696L20.3068 28.0126L20.3049 28.0143Z\"\n                                        fill=\"url(#paint4_radial_69_2953)\" \/>\n                                <\/g>\n                            <\/g>\n                            <defs>\n                                <radialGradient id=\"paint0_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint1_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint2_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint3_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                                <radialGradient id=\"paint4_radial_69_2953\" cx=\"0\" cy=\"0\" r=\"1\"\n                                    gradientUnits=\"userSpaceOnUse\"\n                                    gradientTransform=\"translate(30.4983 32.9703) rotate(-127.835) scale(37.4213 32.9522)\">\n                                    <stop stop-color=\"#00A880\" \/>\n                                    <stop offset=\"1\" stop-color=\"#565DA9\" \/>\n                                <\/radialGradient>\n                            <\/defs>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n                        <div id=\"post-list\">\n\n            <\/div>\n        <\/div>\n\n    <\/div>\n<\/div>\n\n<script type=\"text\/javascript\">\njQuery(function($) {\n    $('#load-more').on('click', function() {\n        var page = $(this).data('page');\n        var newPage = page + 1;\n        var ajaxurl = 'https:\/\/redivium.com\/wp-admin\/admin-ajax.php';\n\n        $.ajax({\n            url: ajaxurl,\n            type: 'POST',\n            data: {\n                page: page,\n                action: 'load_news'\n            },\n            error: function(response) {\n                console.log(response);\n                console.log(ajaxurl);\n            },\n            success: function(response) {\n                console.log(response);\n                $('#post-list').append(response.html);\n                $('#load-more').data('page', newPage);\n\n                if (response.next_page_exists !== true) {\n                    $('#load-more-wrap').hide();\n                }\n            }\n        });\n    });\n});\n<\/script>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-767","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/pages\/767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/comments?post=767"}],"version-history":[{"count":6,"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/pages\/767\/revisions"}],"predecessor-version":[{"id":928,"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/pages\/767\/revisions\/928"}],"wp:attachment":[{"href":"https:\/\/redivium.com\/de\/wp-json\/wp\/v2\/media?parent=767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}